{"id":2862,"date":"2024-07-30T17:07:59","date_gmt":"2024-07-30T10:07:59","guid":{"rendered":"https:\/\/www.dpo.gov.la\/?p=2862"},"modified":"2024-07-31T14:44:56","modified_gmt":"2024-07-31T07:44:56","slug":"dpo-sku-2024","status":"publish","type":"post","link":"https:\/\/www.dpo.gov.la\/en\/dpo-sku-2024\/","title":{"rendered":"\u0eaa\u0e9b\u0e87 \u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e8d\u0ebb\u0e81\u0eaa\u0eb9\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1 \u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ea7\u0ebd\u0e81\u0e87\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81 \u0ea2\u0eb9\u0ec8\u0ea1\u0eb0\u0eab\u0eb2\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0ec4\u0ea5\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2868\" src=\"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-02.jpg\" alt=\"\" width=\"1240\" height=\"1753\" srcset=\"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-02.jpg 1240w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-02-212x300.jpg 212w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-02-724x1024.jpg 724w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-02-768x1086.jpg 768w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-02-1087x1536.jpg 1087w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-02-8x12.jpg 8w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-02-600x848.jpg 600w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2869\" src=\"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-03.jpg\" alt=\"\" width=\"1240\" height=\"1753\" srcset=\"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-03.jpg 1240w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-03-212x300.jpg 212w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-03-724x1024.jpg 724w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-03-768x1086.jpg 768w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-03-1087x1536.jpg 1087w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-03-8x12.jpg 8w, https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/\u0eaa\u0e9b\u0e87-\u0ea1\u0e82-03-600x848.jpg 600w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":2871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[78],"tags":[],"class_list":["post-2862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-78"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0eaa\u0e9b\u0e87 \u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e8d\u0ebb\u0e81\u0eaa\u0eb9\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1 \u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ea7\u0ebd\u0e81\u0e87\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81 \u0ea2\u0eb9\u0ec8\u0ea1\u0eb0\u0eab\u0eb2\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0ec4\u0ea5\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94 - Deposit Protection Office<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dpo.gov.la\/en\/dpo-sku-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0eaa\u0e9b\u0e87 \u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e8d\u0ebb\u0e81\u0eaa\u0eb9\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1 \u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ea7\u0ebd\u0e81\u0e87\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81 \u0ea2\u0eb9\u0ec8\u0ea1\u0eb0\u0eab\u0eb2\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0ec4\u0ea5\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94 - Deposit Protection Office\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dpo.gov.la\/en\/dpo-sku-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Deposit Protection Office\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-30T10:07:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-31T07:44:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-13.52.17.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1809\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DPO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DPO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/\",\"url\":\"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/\",\"name\":\"\u0eaa\u0e9b\u0e87 \u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e8d\u0ebb\u0e81\u0eaa\u0eb9\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1 \u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ea7\u0ebd\u0e81\u0e87\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81 \u0ea2\u0eb9\u0ec8\u0ea1\u0eb0\u0eab\u0eb2\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0ec4\u0ea5\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94 - Deposit Protection Office\",\"isPartOf\":{\"@id\":\"https:\/\/www.dpo.gov.la\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-13.52.17.jpeg\",\"datePublished\":\"2024-07-30T10:07:59+00:00\",\"dateModified\":\"2024-07-31T07:44:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.dpo.gov.la\/#\/schema\/person\/0f3179787f3a7859d8bdab5355810ed2\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#primaryimage\",\"url\":\"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-13.52.17.jpeg\",\"contentUrl\":\"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-13.52.17.jpeg\",\"width\":1809,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dpo.gov.la\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0eaa\u0e9b\u0e87 \u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e8d\u0ebb\u0e81\u0eaa\u0eb9\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1 \u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ea7\u0ebd\u0e81\u0e87\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81 \u0ea2\u0eb9\u0ec8\u0ea1\u0eb0\u0eab\u0eb2\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0ec4\u0ea5\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dpo.gov.la\/#website\",\"url\":\"https:\/\/www.dpo.gov.la\/\",\"name\":\"Deposit Protection Office\",\"description\":\"DPO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dpo.gov.la\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dpo.gov.la\/#\/schema\/person\/0f3179787f3a7859d8bdab5355810ed2\",\"name\":\"DPO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dpo.gov.la\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3b97aeee4054bf539b731226dfed179ef5472d6dd9fa666018262f9e994c37ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3b97aeee4054bf539b731226dfed179ef5472d6dd9fa666018262f9e994c37ec?s=96&d=mm&r=g\",\"caption\":\"DPO\"},\"url\":\"https:\/\/www.dpo.gov.la\/en\/author\/dpo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0eaa\u0e9b\u0e87 \u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e8d\u0ebb\u0e81\u0eaa\u0eb9\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1 \u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ea7\u0ebd\u0e81\u0e87\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81 \u0ea2\u0eb9\u0ec8\u0ea1\u0eb0\u0eab\u0eb2\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0ec4\u0ea5\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94 - Deposit Protection Office","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dpo.gov.la\/en\/dpo-sku-2024\/","og_locale":"en_US","og_type":"article","og_title":"\u0eaa\u0e9b\u0e87 \u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e8d\u0ebb\u0e81\u0eaa\u0eb9\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1 \u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ea7\u0ebd\u0e81\u0e87\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81 \u0ea2\u0eb9\u0ec8\u0ea1\u0eb0\u0eab\u0eb2\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0ec4\u0ea5\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94 - Deposit Protection Office","og_url":"https:\/\/www.dpo.gov.la\/en\/dpo-sku-2024\/","og_site_name":"Deposit Protection Office","article_published_time":"2024-07-30T10:07:59+00:00","article_modified_time":"2024-07-31T07:44:56+00:00","og_image":[{"width":1809,"height":2560,"url":"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-13.52.17.jpeg","type":"image\/jpeg"}],"author":"DPO","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DPO","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/","url":"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/","name":"\u0eaa\u0e9b\u0e87 \u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e8d\u0ebb\u0e81\u0eaa\u0eb9\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1 \u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ea7\u0ebd\u0e81\u0e87\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81 \u0ea2\u0eb9\u0ec8\u0ea1\u0eb0\u0eab\u0eb2\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0ec4\u0ea5\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94 - Deposit Protection Office","isPartOf":{"@id":"https:\/\/www.dpo.gov.la\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-13.52.17.jpeg","datePublished":"2024-07-30T10:07:59+00:00","dateModified":"2024-07-31T07:44:56+00:00","author":{"@id":"https:\/\/www.dpo.gov.la\/#\/schema\/person\/0f3179787f3a7859d8bdab5355810ed2"},"breadcrumb":{"@id":"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dpo.gov.la\/dpo-sku-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#primaryimage","url":"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-13.52.17.jpeg","contentUrl":"https:\/\/www.dpo.gov.la\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-31-at-13.52.17.jpeg","width":1809,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.dpo.gov.la\/dpo-sku-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dpo.gov.la\/"},{"@type":"ListItem","position":2,"name":"\u0eaa\u0e9b\u0e87 \u0eaa\u0eb7\u0e9a\u0e95\u0ecd\u0ec8\u0e8d\u0ebb\u0e81\u0eaa\u0eb9\u0e87\u0eaa\u0ec9\u0eb2\u0e87\u0e84\u0ea7\u0eb2\u0ea1\u0eae\u0eb1\u0e9a\u0eae\u0eb9\u0ec9\u0ec3\u0eab\u0ec9\u0ec1\u0e81\u0ec8\u0eaa\u0eb1\u0e87\u0e84\u0ebb\u0ea1 \u0e81\u0ec8\u0ebd\u0ea7\u0e81\u0eb1\u0e9a\u0ea7\u0ebd\u0e81\u0e87\u0eb2\u0e99\u0e9b\u0ebb\u0e81\u0e9b\u0ec9\u0ead\u0e87\u0ec0\u0e87\u0eb4\u0e99\u0e9d\u0eb2\u0e81 \u0ea2\u0eb9\u0ec8\u0ea1\u0eb0\u0eab\u0eb2\u0ea7\u0eb4\u0e97\u0eb0\u0e8d\u0eb2\u0ec4\u0ea5\u0eaa\u0eb0\u0eab\u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e82\u0e94"}]},{"@type":"WebSite","@id":"https:\/\/www.dpo.gov.la\/#website","url":"https:\/\/www.dpo.gov.la\/","name":"Deposit Protection Office","description":"DPO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dpo.gov.la\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.dpo.gov.la\/#\/schema\/person\/0f3179787f3a7859d8bdab5355810ed2","name":"DPO","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dpo.gov.la\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3b97aeee4054bf539b731226dfed179ef5472d6dd9fa666018262f9e994c37ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b97aeee4054bf539b731226dfed179ef5472d6dd9fa666018262f9e994c37ec?s=96&d=mm&r=g","caption":"DPO"},"url":"https:\/\/www.dpo.gov.la\/en\/author\/dpo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/posts\/2862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/comments?post=2862"}],"version-history":[{"count":1,"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/posts\/2862\/revisions"}],"predecessor-version":[{"id":2870,"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/posts\/2862\/revisions\/2870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/media\/2871"}],"wp:attachment":[{"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/media?parent=2862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/categories?post=2862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dpo.gov.la\/en\/wp-json\/wp\/v2\/tags?post=2862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}